{"id":651,"date":"2018-01-10T16:33:23","date_gmt":"2018-01-10T15:33:23","guid":{"rendered":"https:\/\/www.andrelang-law.de\/?p=651"},"modified":"2018-01-10T16:33:23","modified_gmt":"2018-01-10T15:33:23","slug":"conversion-law","status":"publish","type":"post","link":"https:\/\/andrelang-law.de\/en\/umwandlungsgesetz\/","title":{"rendered":"Carry out the change of legal form in accordance with the Transformation Act"},"content":{"rendered":"<p>Nicht selten sehen die Inhaber eines Unternehmens eine Umstrukturierung Ihres Unternehmens als notwendig an. Das kann viele Gr\u00fcnde haben, sei es die Verm\u00f6gens\u00fcbertragung, die Spaltung, die Verschmelzung mit einer anderen Firma oder die \u00c4nderung der Rechtsform. Hier greift das Umwandlungsgesetz (UmwG). Ich berate als Fachanwalt f\u00fcr Handels- und [link text=&#8220;Gesellschaftsrecht M\u00fcnchen&#8220; id=&#8220;74&#8243;] und Umgebung regelm\u00e4\u00dfig zu rechtlichen Umstrukturierungen und m\u00f6chte Ihnen im Zuge dieses Beitrages das Umwandlungsgesetz genauer erkl\u00e4ren, wie laut diesem der Rechtsformwechsel stattzufinden hat. <\/p>\n<p>##Umwandlungsgesetz &#8211; Wichtige Bestimmungen<\/p>\n<p>Das Umwandlungsgesetz umfasst, wie bereits erw\u00e4hnt, die Umwandlungsarten Verschmelzung, Spaltung und Formwechsel. Die Verm\u00f6gens\u00fcbertragung (Teil- oder Voll\u00fcbertragung) ist keine eigenst\u00e4ndige Umwandlungsart, sondern geht mit einer Verschmelzung oder einer Spaltung einher. An die Spaltungsvorschriften, Verschmelzungsvorschriften etc. m\u00fcssen sich alle Rechtstr\u00e4ger und Gesellschafter des Unternehmens halten, damit die neuen Firmenstrukturen rechtm\u00e4\u00dfig anerkannt werden. Das Umwandlungsgesetz sieht f\u00fcr alle Umwandlungsarten einen Vertrag vor, der bestimmte Angaben enthalten muss. <\/p>\n<p>###Genauerer Blick auf den Rechtsformwechsel <\/p>\n<p>Wenn sich ein Unternehmen dazu entscheidet, seine Rechtsform zu \u00e4ndern, z.B. von einer GmbH zu einer AG \u00fcber zu gehen, so wird dies als Formwechsel bezeichnet. Die Rechtsform zu \u00e4ndern, kann vielerlei Gr\u00fcnde haben. Oft \u00e4ndern sich die Strukturen eines Unternehmens, sodass die bisherige Rechtsform nicht mehr passt. Meist entscheiden sich Rechtstr\u00e4ger auch aus steuerlichen Gr\u00fcnden f\u00fcr einen Formwechsel. Das Umwandlungsgesetz sieht bei \u00c4nderungen der Rechtsform einen genauen Ablauf vor.<\/p>\n<p>Insbesondere folgende Daten m\u00fcssen im erforderlichen Umwandlungsbeschluss aufgef\u00fchrt werden: <\/p>\n<p>&#8211; Die neue Rechtsform des Rechtstr\u00e4gers<br \/>\n&#8211; Der Name oder die Firma des Rechtstr\u00e4gers neuer Rechtsform<br \/>\n&#8211; Beteiligung der bisherigen Anteilsinhaber<br \/>\n&#8211; Art, Zahl und Umfang der Anteile oder Mitgliedschaften<br \/>\n&#8211; Anteilsinhaber und deren Rechte sowie Inhaber besonderer Rechte, wie z.B. Anteile ohne Stimmrecht, &#8211;<br \/>\n Mehrstimmrechtsaktien, Vorzugsaktien, Genussrechte und Schuldverschreibungen.<br \/>\n&#8211; Ein Abfindungsangebot (\u00dcberweisung oder Barabfindung), sofern keine Zustimmung Aller zum Wechsel der Rechtsform vorliegt.<br \/>\n&#8211; Die Folgen des Formwechsels f\u00fcr die Arbeitnehmer<\/p>\n<p>Der Entwurf des Umwandlungsbeschlusses muss sp\u00e4testens einen Monat vor der Versammlung aller Gesellschafter, welche den Formwechsel beschlie\u00dfen soll, an den zust\u00e4ndigen Betriebsrat des formwechselnden Rechtstr\u00e4gers geleitet werden. <\/p>\n<p>###Der identit\u00e4tswahrende Rechtsformwechsel<\/p>\n<p>Das Umwandlungsgesetz regelt den Wechsel der Rechtsform nicht voll und ganz. Unter bestimmten Umst\u00e4nden tritt laut Gesetz der identit\u00e4tswahrende Rechtsformwechsel in Kraft. Das ist der Fall, wenn beispielsweise eine GbR im Laufe ihrer Existenz ein Handelsgewerbe aufnimmt, welches nach Art und Umfang einen auf kaufm\u00e4nnischer Weise eingerichteten Gesch\u00e4ftsbetrieb erfordert. Dann handelt es sich beim Unternehmen laut Umwandlungsgesetz zwangsl\u00e4ufig um eine oHG, unabh\u00e4ngig vom Willen der einzelnen Gesellschafter.<\/p>\n<p>Wenn Sie eine ausf\u00fchrlichere Beratung zum Umwandlungsgesetz und zum Wechsel der Rechtsform oder einer der anderen Umwandlungsarten w\u00fcnschen, so k\u00f6nnen Sie gerne meine Fachanwaltskanzlei andrelang law in M\u00fcnchen kontaktieren und meinen anwaltlichen Rat in Anspruch nehmen. Ich helfe Ihnen gerne. <\/p>\n<p>Weitere interessante Beitr\u00e4ge rund um das Gesellschaftsrecht erwarten Sie auf meinem Blog. <\/p>\n<p><span style=\"font-size: xx-small\"> Copyright Hinweis: \u00a9 Fotolia.com\/sunnychicka<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicht selten sehen die Inhaber eines Unternehmens eine Umstrukturierung Ihres Unternehmens als notwendig an. Das kann viele Gr\u00fcnde haben, sei es die Verm\u00f6gens\u00fcbertragung, die Spaltung, die Verschmelzung mit einer anderen Firma oder die \u00c4nderung der Rechtsform. Hier greift das Umwandlungsgesetz (UmwG). Ich berate als Fachanwalt f\u00fcr Handels- und [link text=&#8220;Gesellschaftsrecht M\u00fcnchen&#8220; id=&#8220;74&#8243;] und Umgebung regelm\u00e4\u00dfig [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":139,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaftsrecht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Umwandlungsgesetz - Formwechsel konform durchf\u00fchren<\/title>\n<meta name=\"description\" content=\"Umwandlungsgesetz | Einfach und konform den Formwechsel durchf\u00fchren \u2713 Bestimmungen \u2713 Pflichtangaben \u2713 Jetzt informieren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andrelang-law.de\/en\/conversion-law\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umwandlungsgesetz - Formwechsel konform durchf\u00fchren\" \/>\n<meta property=\"og:description\" content=\"Umwandlungsgesetz | Einfach und konform den Formwechsel durchf\u00fchren \u2713 Bestimmungen \u2713 Pflichtangaben \u2713 Jetzt informieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andrelang-law.de\/en\/conversion-law\/\" \/>\n<meta property=\"og:site_name\" content=\"Andrelang Law\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-10T15:33:23+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#\\\/schema\\\/person\\\/d455a6285abe5aff392767ca53af4122\"},\"headline\":\"Dem Umwandlungsgesetz konform den Formwechsel durchf\u00fchren\",\"datePublished\":\"2018-01-10T15:33:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Gesellschaftsrecht\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/\",\"url\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/\",\"name\":\"Umwandlungsgesetz - Formwechsel konform durchf\u00fchren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2018-01-10T15:33:23+00:00\",\"description\":\"Umwandlungsgesetz | Einfach und konform den Formwechsel durchf\u00fchren \u2713 Bestimmungen \u2713 Pflichtangaben \u2713 Jetzt informieren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/umwandlungsgesetz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/andrelang-law.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dem Umwandlungsgesetz konform den Formwechsel durchf\u00fchren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#website\",\"url\":\"https:\\\/\\\/andrelang-law.de\\\/\",\"name\":\"Andrelang Law\",\"description\":\"Gesellschaftsrecht M\u00fcnchen\",\"publisher\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/andrelang-law.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#organization\",\"name\":\"Andrelang Law\",\"url\":\"https:\\\/\\\/andrelang-law.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/andrelang-law.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/andrelang-law_logo.png\",\"contentUrl\":\"https:\\\/\\\/andrelang-law.de\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/andrelang-law_logo.png\",\"width\":1096,\"height\":201,\"caption\":\"Andrelang Law\"},\"image\":{\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/andrelang-law.de\\\/#\\\/schema\\\/person\\\/d455a6285abe5aff392767ca53af4122\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/andrelang-law.eu\"],\"url\":\"https:\\\/\\\/andrelang-law.de\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conversion Act - carry out change of legal form in a compliant manner","description":"Conversion Act | Change your legal form easily and compliantly \u2713 Regulations \u2713 Mandatory information \u2713 Inform now.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andrelang-law.de\/en\/conversion-law\/","og_locale":"en_GB","og_type":"article","og_title":"Umwandlungsgesetz - Formwechsel konform durchf\u00fchren","og_description":"Umwandlungsgesetz | Einfach und konform den Formwechsel durchf\u00fchren \u2713 Bestimmungen \u2713 Pflichtangaben \u2713 Jetzt informieren.","og_url":"https:\/\/andrelang-law.de\/en\/conversion-law\/","og_site_name":"Andrelang Law","article_published_time":"2018-01-10T15:33:23+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/#article","isPartOf":{"@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/"},"author":{"name":"admin","@id":"https:\/\/andrelang-law.de\/#\/schema\/person\/d455a6285abe5aff392767ca53af4122"},"headline":"Dem Umwandlungsgesetz konform den Formwechsel durchf\u00fchren","datePublished":"2018-01-10T15:33:23+00:00","mainEntityOfPage":{"@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/andrelang-law.de\/#organization"},"image":{"@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/#primaryimage"},"thumbnailUrl":"","articleSection":["Gesellschaftsrecht"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/andrelang-law.de\/umwandlungsgesetz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/","url":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/","name":"Conversion Act - carry out change of legal form in a compliant manner","isPartOf":{"@id":"https:\/\/andrelang-law.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/#primaryimage"},"image":{"@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/#primaryimage"},"thumbnailUrl":"","datePublished":"2018-01-10T15:33:23+00:00","description":"Conversion Act | Change your legal form easily and compliantly \u2713 Regulations \u2713 Mandatory information \u2713 Inform now.","breadcrumb":{"@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andrelang-law.de\/umwandlungsgesetz\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/andrelang-law.de\/umwandlungsgesetz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/andrelang-law.de\/"},{"@type":"ListItem","position":2,"name":"Dem Umwandlungsgesetz konform den Formwechsel durchf\u00fchren"}]},{"@type":"WebSite","@id":"https:\/\/andrelang-law.de\/#website","url":"https:\/\/andrelang-law.de\/","name":"Andrelang Law","description":"Corporate Law Munich","publisher":{"@id":"https:\/\/andrelang-law.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andrelang-law.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/andrelang-law.de\/#organization","name":"Andrelang Law","url":"https:\/\/andrelang-law.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/andrelang-law.de\/#\/schema\/logo\/image\/","url":"https:\/\/andrelang-law.de\/wp-content\/uploads\/2020\/11\/andrelang-law_logo.png","contentUrl":"https:\/\/andrelang-law.de\/wp-content\/uploads\/2020\/11\/andrelang-law_logo.png","width":1096,"height":201,"caption":"Andrelang Law"},"image":{"@id":"https:\/\/andrelang-law.de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/andrelang-law.de\/#\/schema\/person\/d455a6285abe5aff392767ca53af4122","name":"admin","sameAs":["http:\/\/andrelang-law.eu"],"url":"https:\/\/andrelang-law.de\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/posts\/651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/comments?post=651"}],"version-history":[{"count":0,"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/posts\/651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andrelang-law.de\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/media?parent=651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/categories?post=651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andrelang-law.de\/en\/wp-json\/wp\/v2\/tags?post=651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}